{"id":1659,"date":"2023-01-12T10:00:27","date_gmt":"2023-01-12T10:00:27","guid":{"rendered":"https:\/\/gastrounika.com\/gastrounika-caviar-katalog\/"},"modified":"2023-03-09T11:50:15","modified_gmt":"2023-03-09T11:50:15","slug":"gastrounika-caviar-katalog","status":"publish","type":"page","link":"https:\/\/gastrounika.com\/da\/gastrounika-caviar-katalog\/","title":{"rendered":"GASTROunika-Caviar produktkatalog"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1659\" class=\"elementor elementor-1659 elementor-908\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0ee3e5f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0ee3e5f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-92a025c\" data-id=\"92a025c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b88184 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"5b88184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">GASTROunika-Caviar<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3258a8d\" data-id=\"3258a8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c711a9b elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"c711a9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/gastrounika.com\/da\/gastrounika-caviar-katalog\/#RBC\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ROYAL BELGIAN CAVIAR<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e19c14d\" data-id=\"e19c14d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14a41a7 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"14a41a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/gastrounika.com\/da\/gastrounika-caviar-katalog\/#elegance\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CAVIAR ELEGANCE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-55fc0b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55fc0b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0a57da\" data-id=\"a0a57da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cf884e elementor-widget elementor-widget-heading\" data-id=\"3cf884e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"RBC\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ROYAL BELGIAN CAVIAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afc35f7 eael-product-list-column-tablet-2 eael-product-list-column-2 elementor-widget elementor-widget-eicon-woocommerce\" data-id=\"afc35f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eicon-woocommerce.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-grid  list\" id=\"eael-product-grid\" data-widget-id=\"afc35f7\" data-page-id=\"1659\" data-nonce=\"ebce5d047a\" >\n            <div class=\"woocommerce\">\n                <ul class=\"products eael-post-appender eael-post-appender-afc35f7\" data-ssi-desktop=\"no\" data-ssi-tablet=\"\" data-ssi-mobile=\"\" data-layout-mode=\"list\"><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/RBC_Gold.png\" class=\"attachment-full size-full\" alt=\"Gold Caviar\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-gold-royal-belgian-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Gold Caviar<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-gold-royal-belgian-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1762\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"1762\" data-product_sku=\"Gold RBC\" aria-label=\"V\u00e6lg muligheder for &ldquo;Gold Caviar&rdquo;\" rel=\"nofollow\">Valgmuligheder<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1762\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/RBC_Platinum.png\" class=\"attachment-full size-full\" alt=\"Platinum Caviar\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-royal-belgian-caviar-platinum\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Platinum Caviar<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-royal-belgian-caviar-platinum\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1715\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"1715\" data-product_sku=\"Platinum RBC\" aria-label=\"V\u00e6lg muligheder for &ldquo;Platinum Caviar&rdquo;\" rel=\"nofollow\">Valgmuligheder<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1715\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/RBC_oscietra.png\" class=\"attachment-full size-full\" alt=\"Osietra Caviar\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-osietra-royal-belgian-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Osietra Caviar<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-osietra-royal-belgian-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1775\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"1775\" data-product_sku=\"Osietra RBC\" aria-label=\"V\u00e6lg muligheder for &ldquo;Osietra Caviar&rdquo;\" rel=\"nofollow\">Valgmuligheder<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1775\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/RBC_oscietra_blonde.png\" class=\"attachment-full size-full\" alt=\"Osietra Blonde Caviar\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-royal-belgian-caviar-osietra-blonde\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Osietra Blonde Caviar<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-royal-belgian-caviar-osietra-blonde\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1755\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1755\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Osietra Blonde Caviar&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1755\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/RBC_white_pearl.png\" class=\"attachment-full size-full\" alt=\"White Pearl\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-white-pearl-belgian-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">White Pearl<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-white-pearl-belgian-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1728\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1728\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;White Pearl&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1728\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/RBC_beluga.png\" class=\"attachment-full size-full\" alt=\"Beluga Caviar\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-royal-belgian-caviar-beluga\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Beluga Caviar<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-royal-belgian-caviar-beluga\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1692\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1692\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Beluga Caviar&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1692\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/tastingbox2.jpg\" class=\"attachment-full size-full\" alt=\"Tasting Box Caviar \u2013 Gold + Platinum + Osietra\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/tasting-box-gold-platinum-osietra_dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Tasting Box Caviar \u2013 Gold + Platinum + Osietra<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/tasting-box-gold-platinum-osietra_dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1707\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"1707\" data-product_sku=\"\" aria-label=\"V\u00e6lg muligheder for &ldquo;Tasting Box Caviar \u2013 Gold + Platinum + Osietra&rdquo;\" rel=\"nofollow\">Valgmuligheder<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1707\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><\/ul>            <\/div>\n        <\/div>\n\n        <script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                var $scope = jQuery(\".elementor-element-afc35f7\");\n                var $products = $('.products', $scope);\n                var $layout_mode = $products.data('layout-mode');\n                \n                if ( $layout_mode === 'masonry' ) {\n                    \/\/ init isotope\n                    var $isotope_products = $products.isotope({\n                        itemSelector: \"li.product\",\n                        layoutMode: $layout_mode,\n                        percentPosition: true\n                    });\n\n                    $isotope_products.imagesLoaded().progress( function() {\n                        $isotope_products.isotope('layout');\n                    })\n                    \n                }\n            });\n        <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c8ba2f elementor-widget elementor-widget-heading\" data-id=\"2c8ba2f\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"elegance\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAVIAR ELEGANCE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd8426 eael-product-list-column-tablet-2 eael-product-list-column-2 elementor-widget elementor-widget-eicon-woocommerce\" data-id=\"ccd8426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eicon-woocommerce.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-grid  list\" id=\"eael-product-grid\" data-widget-id=\"ccd8426\" data-page-id=\"1659\" data-nonce=\"ebce5d047a\" >\n            <div class=\"woocommerce\">\n                <ul class=\"products eael-post-appender eael-post-appender-ccd8426\" data-ssi-desktop=\"no\" data-ssi-tablet=\"\" data-ssi-mobile=\"\" data-layout-mode=\"list\"><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/Elegance_Ossetra_Classic.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Ossetra Classic\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-ossetra-classic-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Ossetra Classic<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-ossetra-classic-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1706\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1706\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Ossetra Classic&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1706\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/Elegance_Ossetra_Royal.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Ossetra Royal\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-elegance-caviar-ossetra-royal\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Ossetra Royal<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-elegance-caviar-ossetra-royal\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1740\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1740\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Ossetra Royal&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1740\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/Elegance_Ossetra_Imperial.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Ossetra Imperial\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-ossetra-imperial-caviar-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Ossetra Imperial<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-ossetra-imperial-caviar-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1691\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1691\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Ossetra Imperial&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1691\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/Elegance_Ossetra_Imperial_Gold.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Ossetra Imperial Gold\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-ossetra-imperial-gold-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Ossetra Imperial Gold<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-ossetra-imperial-gold-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1730\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1730\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Ossetra Imperial Gold&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1730\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/Elegance_Beluga-Sevruga.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Beluga-Sevruga\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-beluga-sevruga-elegance-dk\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Beluga-Sevruga<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-caviar-beluga-sevruga-elegance-dk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1777\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1777\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Beluga-Sevruga&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1777\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2022\/11\/Elegance_Beluga.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Beluga\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-elegance-caviar-beluga\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Beluga<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/gastrounika-elegance-caviar-beluga\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1748\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"1748\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Beluga&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1748\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><li class=\"product  eael-product-list-preset-1\">\n    <div class=\"eael-product-wrap\">\n        <div class=\"product-image-wrap\">\n            <div class=\"image-wrap\">\n                <span class=\"eael-onsale outofstock  \">Out of stock<\/span><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/gastrounika.com\/wp-content\/uploads\/2025\/12\/GASTROunika_Caviar_Elegance_Beluga-Sterlet-1.png\" class=\"attachment-full size-full\" alt=\"Elegance Caviar Beluga-Sterlet\" loading=\"eager\" \/>            <\/div>\n        <\/div>\n        <div class=\"product-details-wrap\">\n            <div class=\"eael-product-title\">\n                                <a href=\"https:\/\/gastrounika.com\/da\/vare\/elegance-caviar-beluga-sterlet\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Elegance Caviar Beluga-Sterlet<\/h2><\/a><\/div>\n            <ul class=\"icons-wrap details-block-style\">\n                                <li class=\"add-to-cart\"><a href=\"https:\/\/gastrounika.com\/da\/vare\/elegance-caviar-beluga-sterlet\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3602\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"3602\" data-product_sku=\"\" aria-label=\"L\u00e6s mere om &ldquo;Elegance Caviar Beluga-Sterlet&rdquo;\" rel=\"nofollow\" data-success_message=\"\">F\u00e5 mere at vide<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3602\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n\n                                            <\/ul>\n                    <\/div>\n    <\/div>\n<\/li><\/ul>            <\/div>\n        <\/div>\n\n        <script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                var $scope = jQuery(\".elementor-element-ccd8426\");\n                var $products = $('.products', $scope);\n                var $layout_mode = $products.data('layout-mode');\n                \n                if ( $layout_mode === 'masonry' ) {\n                    \/\/ init isotope\n                    var $isotope_products = $products.isotope({\n                        itemSelector: \"li.product\",\n                        layoutMode: $layout_mode,\n                        percentPosition: true\n                    });\n\n                    $isotope_products.imagesLoaded().progress( function() {\n                        $isotope_products.isotope('layout');\n                    })\n                    \n                }\n            });\n        <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GASTROunika-Caviar ROYAL BELGIAN CAVIAR CAVIAR ELEGANCE ROYAL BELGIAN CAVIAR Gold Caviar Valgmuligheder Platinum Caviar Valgmuligheder Osietra Caviar Valgmuligheder Stock Out Osietra Blonde Caviar F\u00e5 mere at vide Stock Out White Pearl Caviar F\u00e5 mere at vide Stock Out Beluga Caviar F\u00e5 mere at vide GASTROunika Caviar Tasting Experience | Gold\/Platinum\/Osietra Valgmuligheder CAVIAR ELEGANCE Stock Out [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2500,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1659","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/pages\/1659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/comments?post=1659"}],"version-history":[{"count":10,"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/pages\/1659\/revisions"}],"predecessor-version":[{"id":2531,"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/pages\/1659\/revisions\/2531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/media\/2500"}],"wp:attachment":[{"href":"https:\/\/gastrounika.com\/da\/wp-json\/wp\/v2\/media?parent=1659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}